{"id":7719,"date":"2021-09-14T17:28:45","date_gmt":"2021-09-14T15:28:45","guid":{"rendered":"https:\/\/ateliersi.it\/si\/?p=7719"},"modified":"2022-08-24T14:05:22","modified_gmt":"2022-08-24T12:05:22","slug":"perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021","status":"publish","type":"post","link":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/","title":{"rendered":"PERDERSI IN QUESTO INCANTESIMO Invito a danzare in omaggio a Franco Battiato, 25.09.2021"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7758 alignleft\" src=\"https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg\" alt=\"\" width=\"615\" height=\"463\" srcset=\"https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg 615w, https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy-300x226.jpg 300w\" sizes=\"auto, (max-width: 615px) 100vw, 615px\" \/>sabato 25 settembre, h. 21.30 <\/span><span style=\"font-weight: 400;\">@Arena Orfeonica di Broccaindosso<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">PERDERSI IN QUESTO INCANTESIMO<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Invito a danzare in omaggio a Franco Battiato<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">durata: 45 minuti<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">nell\u2019ambito di <a href=\"https:\/\/ateliersi.it\/si\/quando-prende-corpo-opening-si-2021-22-25-09-2021\/\" target=\"_blank\" rel=\"noopener\">QUANDO PRENDE CORPO Opening S\u00ec 2021\/22<\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un luogo laboratoriale e una gara di ballo all\u2019aperto creati da Ateliersi con l&#8217;euforica complicit\u00e0 di Cristina Kristal Rizzo.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Nel meraviglioso spazio all\u2019aperto dell\u2019Arena Orfeonica verranno disegnati dei cerchi sul dancefloor.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Il centro di gravit\u00e0 dentro il quale ognuno baller\u00e0 Battiato verr\u00e0 assegnato al momento della prenotazione.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Il dj set sar\u00e0 a cura di Dj Spike.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Sar\u00e0 bellissimo vedervi danzare!<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"font-weight: 400;\">\ud83d\udcfb In diretta la radiocronaca della gara di ballo a cura di NEU RADIO.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">MODALIT\u00c0 di PARTECIPAZIONE \ud83e\udd9a<br \/>\n<\/span><span style=\"font-weight: 400;\">Si potr\u00e0 partecipare danzando o vedendo danzare. A chi danza sar\u00e0 attribuito un cerchio disegnato sul dance floor. I cerchi sono limitati, se vuoi danzare affrettati a prenotare il tuo!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Potrai effettuare la tua scelta\u00a0<\/span>(VOGLIO DANZARE oppure VOGLIO VEDERTI DANZARE)\u00a0nel momento dell&#8217;acquisto del biglietto\u00a0unico per la serata di <a href=\"https:\/\/ateliersi.it\/si\/quando-prende-corpo-opening-si-2021-22-25-09-2021\/\" target=\"_blank\" rel=\"noopener\">QUANDO PRENDE CORPO Opening S\u00ec 2021\/22<\/a> (10\u20ac intero con consumazione) &gt; <a href=\"https:\/\/www.vivaticket.com\/it\/biglietto\/quando-prende-corpo-opening-si-2021\/164273\" target=\"_blank\" rel=\"noopener\">Vivaticket<\/a><\/p>\n<p><span style=\"font-weight: 400;\">Per qualsiasi dubbio contattaci a prenotazioni@ateliersi.it scrivendo il tuo numero se vuoi essere richiamat* e assistit* nella fase dell&#8217;acquisto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">ALLENAMENTO NEI GIORNI PRECEDENTI \ud83e\udd8e<br \/>\n<\/span><span style=\"font-weight: 400;\">Mercoled\u00ec 22 e gioved\u00ec 23 settembre dalle ore 19.00 alle 20.30 sar\u00e0 possibile venirsi ad allenare al ballo. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">L\u2019allenamento sar\u00e0 guidato da Ateliersi e si svolger\u00e0 all\u2019Atelier S\u00ec in Via San Vitale 69.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">\u00c8 necessaria la prenotazione scrivendo a <\/span><span style=\"font-weight: 400;\">prenotazioni@ateliersi.it<\/span><\/p>\n<p><span style=\"font-weight: 400;\">FEEL SECURE \ud83e\udda6<br \/>\n<\/span>&#8220;Perdersi in un incantesimo&#8221; \u00e8 un laboratorio e si svolger\u00e0 nel rispetto di tutte le misure di sicurezza anti-covid19.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>sabato 25 settembre, h. 21.30 @Arena Orfeonica di Broccaindosso PERDERSI IN QUESTO INCANTESIMO Invito a danzare in omaggio a Franco&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7758,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-7719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programma-2021-22"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PERDERSI IN QUESTO INCANTESIMO Invito a danzare in omaggio a Franco Battiato, 25.09.2021 - S\u00ec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PERDERSI IN QUESTO INCANTESIMO Invito a danzare in omaggio a Franco Battiato, 25.09.2021 - S\u00ec\" \/>\n<meta property=\"og:description\" content=\"sabato 25 settembre, h. 21.30 @Arena Orfeonica di Broccaindosso PERDERSI IN QUESTO INCANTESIMO Invito a danzare in omaggio a Franco...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00ec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/si.ateliersi\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-14T15:28:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-24T12:05:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"615\" \/>\n\t<meta property=\"og:image:height\" content=\"463\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"D1gh3z_1975\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AtelierSi\" \/>\n<meta name=\"twitter:site\" content=\"@AtelierSi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"D1gh3z_1975\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PERDERSI IN QUESTO INCANTESIMO Invito a danzare in omaggio a Franco Battiato, 25.09.2021 - S\u00ec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/","og_locale":"it_IT","og_type":"article","og_title":"PERDERSI IN QUESTO INCANTESIMO Invito a danzare in omaggio a Franco Battiato, 25.09.2021 - S\u00ec","og_description":"sabato 25 settembre, h. 21.30 @Arena Orfeonica di Broccaindosso PERDERSI IN QUESTO INCANTESIMO Invito a danzare in omaggio a Franco...","og_url":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/","og_site_name":"S\u00ec","article_publisher":"https:\/\/www.facebook.com\/si.ateliersi","article_published_time":"2021-09-14T15:28:45+00:00","article_modified_time":"2022-08-24T12:05:22+00:00","og_image":[{"width":615,"height":463,"url":"https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg","type":"image\/jpeg"}],"author":"D1gh3z_1975","twitter_card":"summary_large_image","twitter_creator":"@AtelierSi","twitter_site":"@AtelierSi","twitter_misc":{"Scritto da":"D1gh3z_1975","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/#article","isPartOf":{"@id":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/"},"author":{"name":"D1gh3z_1975","@id":"https:\/\/ateliersi.it\/si\/#\/schema\/person\/91e4317416e640b043a6d571b095e9fe"},"headline":"PERDERSI IN QUESTO INCANTESIMO Invito a danzare in omaggio a Franco Battiato, 25.09.2021","datePublished":"2021-09-14T15:28:45+00:00","dateModified":"2022-08-24T12:05:22+00:00","mainEntityOfPage":{"@id":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/"},"wordCount":268,"publisher":{"@id":"https:\/\/ateliersi.it\/si\/#organization"},"image":{"@id":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg","articleSection":["Programma 2021\/22"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/","url":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/","name":"PERDERSI IN QUESTO INCANTESIMO Invito a danzare in omaggio a Franco Battiato, 25.09.2021 - S\u00ec","isPartOf":{"@id":"https:\/\/ateliersi.it\/si\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/#primaryimage"},"image":{"@id":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg","datePublished":"2021-09-14T15:28:45+00:00","dateModified":"2022-08-24T12:05:22+00:00","breadcrumb":{"@id":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/#primaryimage","url":"https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg","contentUrl":"https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg","width":615,"height":463},{"@type":"BreadcrumbList","@id":"https:\/\/ateliersi.it\/si\/perdersi-in-questo-incantesimo-invito-a-danzare-in-omaggio-a-franco-battiato-25-09-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ateliersi.it\/si\/"},{"@type":"ListItem","position":2,"name":"PERDERSI IN QUESTO INCANTESIMO Invito a danzare in omaggio a Franco Battiato, 25.09.2021"}]},{"@type":"WebSite","@id":"https:\/\/ateliersi.it\/si\/#website","url":"https:\/\/ateliersi.it\/si\/","name":"S\u00ec","description":"","publisher":{"@id":"https:\/\/ateliersi.it\/si\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ateliersi.it\/si\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ateliersi.it\/si\/#organization","name":"S\u00ec \u2013 Ateliersi","url":"https:\/\/ateliersi.it\/si\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ateliersi.it\/si\/#\/schema\/logo\/image\/","url":"https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2015\/09\/cropped-si_head_1516.png","contentUrl":"https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2015\/09\/cropped-si_head_1516.png","width":512,"height":512,"caption":"S\u00ec \u2013 Ateliersi"},"image":{"@id":"https:\/\/ateliersi.it\/si\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/si.ateliersi","https:\/\/x.com\/AtelierSi","https:\/\/www.instagram.com\/si.ateliersi\/"]},{"@type":"Person","@id":"https:\/\/ateliersi.it\/si\/#\/schema\/person\/91e4317416e640b043a6d571b095e9fe","name":"D1gh3z_1975","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ededc0273e000444c333a60add515e7ec6b9e86fbfd367a63476a4a85ecb727d?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ededc0273e000444c333a60add515e7ec6b9e86fbfd367a63476a4a85ecb727d?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ededc0273e000444c333a60add515e7ec6b9e86fbfd367a63476a4a85ecb727d?s=96&d=monsterid&r=g","caption":"D1gh3z_1975"}}]}},"rttpg_featured_image_url":{"full":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg",615,463,false],"landscape":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg",615,463,false],"portraits":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg",615,463,false],"thumbnail":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy-150x150.jpg",150,150,true],"medium":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy-300x226.jpg",300,226,true],"large":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg",615,463,false],"1536x1536":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg",615,463,false],"2048x2048":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy.jpg",615,463,false],"blog-type-1-small":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy-220x220.jpg",220,220,true],"blog-type-1-medium":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy-250x250.jpg",250,250,true],"blog-type-1-big":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy-338x338.jpg",338,338,true],"blog-type-3-small":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy-196x111.jpg",196,111,true],"blog-type-3-medium":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy-218x124.jpg",218,124,true],"blog-type-3-big":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy-300x170.jpg",300,170,true],"blog-type-4-small":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy-304x172.jpg",304,172,true],"blog-type-4-medium":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy-338x191.jpg",338,191,true],"blog-type-5-big":["https:\/\/ateliersi.it\/si\/wp-content\/uploads\/2021\/09\/battiato_03_VHS-copy-460x260.jpg",460,260,true]},"rttpg_author":{"display_name":"D1gh3z_1975","author_link":"https:\/\/ateliersi.it\/si\/author\/d1gh3z_1975\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/ateliersi.it\/si\/category\/programma-2021-22\/\" rel=\"category tag\">Programma 2021\/22<\/a>","rttpg_excerpt":"sabato 25 settembre, h. 21.30 @Arena Orfeonica di Broccaindosso PERDERSI IN QUESTO INCANTESIMO Invito a danzare in omaggio a Franco...","_links":{"self":[{"href":"https:\/\/ateliersi.it\/si\/wp-json\/wp\/v2\/posts\/7719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ateliersi.it\/si\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ateliersi.it\/si\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ateliersi.it\/si\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ateliersi.it\/si\/wp-json\/wp\/v2\/comments?post=7719"}],"version-history":[{"count":1,"href":"https:\/\/ateliersi.it\/si\/wp-json\/wp\/v2\/posts\/7719\/revisions"}],"predecessor-version":[{"id":8207,"href":"https:\/\/ateliersi.it\/si\/wp-json\/wp\/v2\/posts\/7719\/revisions\/8207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ateliersi.it\/si\/wp-json\/wp\/v2\/media\/7758"}],"wp:attachment":[{"href":"https:\/\/ateliersi.it\/si\/wp-json\/wp\/v2\/media?parent=7719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ateliersi.it\/si\/wp-json\/wp\/v2\/categories?post=7719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ateliersi.it\/si\/wp-json\/wp\/v2\/tags?post=7719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}